{"id":83,"date":"2018-03-19T10:36:57","date_gmt":"2018-03-19T07:36:57","guid":{"rendered":"http:\/\/nngu.constructor.loc\/?page_id=83"},"modified":"2018-03-19T10:36:57","modified_gmt":"2018-03-19T07:36:57","slug":"onlajn-obuchenie","status":"publish","type":"page","link":"http:\/\/ioo.msite.unn.ru\/en\/obrazovanie\/onlajn-obuchenie\/","title":{"rendered":"\u041e\u043d\u043b\u0430\u0439\u043d \u043e\u0431\u0443\u0447\u0435\u043d\u0438\u0435"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":0,"parent":65,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"http:\/\/ioo.msite.unn.ru\/en\/wp-json\/wp\/v2\/pages\/83"}],"collection":[{"href":"http:\/\/ioo.msite.unn.ru\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/ioo.msite.unn.ru\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/ioo.msite.unn.ru\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"http:\/\/ioo.msite.unn.ru\/en\/wp-json\/wp\/v2\/comments?post=83"}],"version-history":[{"count":0,"href":"http:\/\/ioo.msite.unn.ru\/en\/wp-json\/wp\/v2\/pages\/83\/revisions"}],"up":[{"embeddable":true,"href":"http:\/\/ioo.msite.unn.ru\/en\/wp-json\/wp\/v2\/pages\/65"}],"wp:attachment":[{"href":"http:\/\/ioo.msite.unn.ru\/en\/wp-json\/wp\/v2\/media?parent=83"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}